{"id":17170,"count":1,"description":"","link":"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/","name":"Nanocompositi","slug":"nanocompositi","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nanocompositi Archivi - Alimentibevande.it<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nanocompositi Archivi - Alimentibevande.it\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/\" \/>\n<meta property=\"og:site_name\" content=\"Alimentibevande.it\" \/>\n<meta property=\"og:image\" content=\"https:\/\/static.tecnichenuove.it\/alimentibevande\/2026\/03\/Logo_Alimentibevande.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/tag\\\/nanocompositi\\\/\",\"url\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/tag\\\/nanocompositi\\\/\",\"name\":\"Nanocompositi Archivi - Alimentibevande.it\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/tag\\\/nanocompositi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/tag\\\/nanocompositi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nanocompositi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/\",\"name\":\"Alimentibevande.it\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/#organization\",\"name\":\"Tecniche Nuove\",\"url\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/static.tecnichenuove.it\\\/alimentibevande\\\/2026\\\/03\\\/tecniche-nuove.png\",\"contentUrl\":\"https:\\\/\\\/static.tecnichenuove.it\\\/alimentibevande\\\/2026\\\/03\\\/tecniche-nuove.png\",\"width\":620,\"height\":620,\"caption\":\"Tecniche Nuove\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alimentibevande.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MacchineAlimentariNews\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/macchinealimentari\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nanocompositi Archivi - Alimentibevande.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/","og_locale":"en_US","og_type":"article","og_title":"Nanocompositi Archivi - Alimentibevande.it","og_url":"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/","og_site_name":"Alimentibevande.it","og_image":[{"width":1200,"height":675,"url":"https:\/\/static.tecnichenuove.it\/alimentibevande\/2026\/03\/Logo_Alimentibevande.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/","url":"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/","name":"Nanocompositi Archivi - Alimentibevande.it","isPartOf":{"@id":"https:\/\/www.alimentibevande.it\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.alimentibevande.it\/en\/tag\/nanocompositi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.alimentibevande.it\/en\/"},{"@type":"ListItem","position":2,"name":"Nanocompositi"}]},{"@type":"WebSite","@id":"https:\/\/www.alimentibevande.it\/en\/#website","url":"https:\/\/www.alimentibevande.it\/en\/","name":"Alimentibevande.it","description":"","publisher":{"@id":"https:\/\/www.alimentibevande.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alimentibevande.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.alimentibevande.it\/en\/#organization","name":"Tecniche Nuove","url":"https:\/\/www.alimentibevande.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.alimentibevande.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/static.tecnichenuove.it\/alimentibevande\/2026\/03\/tecniche-nuove.png","contentUrl":"https:\/\/static.tecnichenuove.it\/alimentibevande\/2026\/03\/tecniche-nuove.png","width":620,"height":620,"caption":"Tecniche Nuove"},"image":{"@id":"https:\/\/www.alimentibevande.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MacchineAlimentariNews","https:\/\/www.linkedin.com\/showcase\/macchinealimentari"]}]}},"_links":{"self":[{"href":"https:\/\/www.alimentibevande.it\/en\/wp-json\/wp\/v2\/tags\/17170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alimentibevande.it\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.alimentibevande.it\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.alimentibevande.it\/en\/wp-json\/wp\/v2\/posts?tags=17170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}